{"id":3649,"date":"2022-12-23T14:18:13","date_gmt":"2022-12-23T13:18:13","guid":{"rendered":"https:\/\/hundertwasser-schule.de\/?p=3649"},"modified":"2022-12-23T14:33:51","modified_gmt":"2022-12-23T13:33:51","slug":"weihnachts-kiko","status":"publish","type":"post","link":"http:\/\/hundertwasser-schule.de\/sr\/weihnachts-kiko\/","title":{"rendered":"Weihnachts-KIKO"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3649\" class=\"elementor elementor-3649\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18e63ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18e63ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e62f3e\" data-id=\"2e62f3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e22e21f elementor-widget elementor-widget-text-editor\" data-id=\"e22e21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: #ff0000;\">Advent, Advent \u2013 das 4. Lichtlein brennt<\/span><\/h1><p>Die Weihnachtsferien stehen vor der T\u00fcr und endlich startet die KIKO. Zum Gl\u00fcck waren inzwischen wieder viele Kinder und Erwachsene nach der heftigen Krankenwelle dabei und konnten die verschiedenen Darbietungen und die Weihnachtsgeschichte in weihnachtlicher Stimmung mit viel Kerzenschein genie\u00dfen.<\/p><p>Es wurde getanzt, gerappt, gesungen, zugeh\u00f6rt, musiziert und manche fragten sich bestimmt, wie \u00fcberhaupt so ein tolles Programm geprobt und realisiert werden konnte, nachdem zeitweilig wegen Krankheiten die Klassen leergefegt waren. Daher erhielten alle Beteiligten viel Applaus und konnten stolz von der B\u00fchne treten.<\/p><p>Zur KIKO durften die Geburtstage, die Aufl\u00f6sung des R\u00e4tsels und einige Sportehrungen nicht fehlen. So gab es sowohl Bronze-, Silber- und sogar Goldauszeichnungen im Bereich des Schwimmens zu vergeben.<\/p><p>Im Namen aller Kolleg*innen und Mitarbeiter*innen w\u00fcnschen wir fr\u00f6hliche Festtage mit Sternenglanz, erholsame Ferien und alles Gute f\u00fcr 2023! Am 09.01.2023 begr\u00fc\u00dfen wir alle Kinder wieder herzlich in der Hundertwasser-Schule und starten hoffentlich gesund ins Jahr!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85f0d69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85f0d69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a20a011\" data-id=\"a20a011\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-916e48c elementor-widget elementor-widget-gallery\" data-id=\"916e48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/hundertwasser-schule.de\/wp-content\/uploads\/2022\/12\/IMG-20221222-WA0014.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"916e48c\" data-elementor-lightbox-title=\"IMG-20221222-WA0014\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYzNiwidXJsIjoiaHR0cHM6XC9cL2h1bmRlcnR3YXNzZXItc2NodWxlLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8xMlwvSU1HLTIwMjIxMjIyLVdBMDAxNC5qcGciLCJzbGlkZXNob3ciOiI5MTZlNDhjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/hundertwasser-schule.de\/wp-content\/uploads\/2022\/12\/IMG-20221222-WA0014-225x300.jpg\" data-width=\"150\" data-height=\"200\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eaa5c8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eaa5c8b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50a75a6\" data-id=\"50a75a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e619391 elementor-widget elementor-widget-video\" data-id=\"e619391\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"http:\/\/hundertwasser-schule.de\/wp-content\/uploads\/2022\/12\/VID-20221222-WA0016.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\" poster=\"http:\/\/hundertwasser-schule.de\/wp-content\/uploads\/2022\/12\/IMG-20221222-WA0022.jpg\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Advent, Advent \u2013 das 4. Lichtlein brennt Die Weihnachtsferien stehen vor der T\u00fcr und endlich startet die KIKO. Zum Gl\u00fcck waren inzwischen wieder viele Kinder und Erwachsene nach der heftigen Krankenwelle dabei und konnten die verschiedenen Darbietungen und die Weihnachtsgeschichte in weihnachtlicher Stimmung mit viel Kerzenschein genie\u00dfen. Es wurde getanzt, gerappt, gesungen, zugeh\u00f6rt, musiziert und [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3649","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"_links":{"self":[{"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/posts\/3649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/comments?post=3649"}],"version-history":[{"count":5,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/posts\/3649\/revisions"}],"predecessor-version":[{"id":3661,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/posts\/3649\/revisions\/3661"}],"wp:attachment":[{"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/media?parent=3649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/categories?post=3649"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hundertwasser-schule.de\/sr\/wp-json\/wp\/v2\/tags?post=3649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}